{"id":1052,"date":"2024-08-26T10:26:08","date_gmt":"2024-08-26T08:26:08","guid":{"rendered":"https:\/\/livondo.com\/livondo-white-label-private-label-medizinprodukte\/"},"modified":"2026-06-12T15:55:39","modified_gmt":"2026-06-12T13:55:39","slug":"livondo-white-label-private-label-medical-devices","status":"publish","type":"page","link":"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/","title":{"rendered":"Sustainability"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":1068,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1052","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sustainable White Label &amp; Private Label Medical Products<\/title>\n<meta name=\"description\" content=\"LIVONDO, as a provider of white label &amp; private label medical products as well as natural cosmetics, considers sustainability to be an important concern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sustainable White Label &amp; Private Label Medical Products\" \/>\n<meta property=\"og:description\" content=\"LIVONDO, as a provider of white label &amp; private label medical products as well as natural cosmetics, considers sustainability to be an important concern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/\" \/>\n<meta property=\"og:site_name\" content=\"Livondo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-12T13:55:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livondo.com\\\/en\\\/services\\\/livondo-white-label-private-label-medical-devices\\\/\",\"url\":\"https:\\\/\\\/livondo.com\\\/en\\\/services\\\/livondo-white-label-private-label-medical-devices\\\/\",\"name\":\"Sustainable White Label & Private Label Medical Products\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livondo.com\\\/en\\\/#website\"},\"datePublished\":\"2024-08-26T08:26:08+00:00\",\"dateModified\":\"2026-06-12T13:55:39+00:00\",\"description\":\"LIVONDO, as a provider of white label & private label medical products as well as natural cosmetics, considers sustainability to be an important concern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livondo.com\\\/en\\\/services\\\/livondo-white-label-private-label-medical-devices\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/livondo.com\\\/en\\\/services\\\/livondo-white-label-private-label-medical-devices\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livondo.com\\\/en\\\/services\\\/livondo-white-label-private-label-medical-devices\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/livondo.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/livondo.com\\\/en\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sustainability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livondo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/livondo.com\\\/en\\\/\",\"name\":\"Livondo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/livondo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sustainable White Label & Private Label Medical Products","description":"LIVONDO, as a provider of white label & private label medical products as well as natural cosmetics, considers sustainability to be an important concern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/","og_locale":"en_US","og_type":"article","og_title":"Sustainable White Label & Private Label Medical Products","og_description":"LIVONDO, as a provider of white label & private label medical products as well as natural cosmetics, considers sustainability to be an important concern.","og_url":"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/","og_site_name":"Livondo","article_modified_time":"2026-06-12T13:55:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/","url":"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/","name":"Sustainable White Label & Private Label Medical Products","isPartOf":{"@id":"https:\/\/livondo.com\/en\/#website"},"datePublished":"2024-08-26T08:26:08+00:00","dateModified":"2026-06-12T13:55:39+00:00","description":"LIVONDO, as a provider of white label & private label medical products as well as natural cosmetics, considers sustainability to be an important concern.","breadcrumb":{"@id":"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/livondo.com\/en\/services\/livondo-white-label-private-label-medical-devices\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/livondo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/livondo.com\/en\/services\/"},{"@type":"ListItem","position":3,"name":"Sustainability"}]},{"@type":"WebSite","@id":"https:\/\/livondo.com\/en\/#website","url":"https:\/\/livondo.com\/en\/","name":"Livondo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/livondo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/pages\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/comments?post=1052"}],"version-history":[{"count":4,"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/pages\/1052\/revisions"}],"predecessor-version":[{"id":1480,"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/pages\/1052\/revisions\/1480"}],"up":[{"embeddable":true,"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/pages\/1068"}],"wp:attachment":[{"href":"https:\/\/livondo.com\/en\/wp-json\/wp\/v2\/media?parent=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}